{"id":7878,"date":"2026-03-20T08:53:37","date_gmt":"2026-03-20T11:53:37","guid":{"rendered":"https:\/\/radiobeat97.com.ar\/beat\/?p=7878"},"modified":"2026-03-19T08:54:18","modified_gmt":"2026-03-19T11:54:18","slug":"puesta-en-valor-del-parque-de-las-tejas-mas-juegos-para-ninos-iluminacion-y-espacios-para-actividad-fisica","status":"publish","type":"post","link":"https:\/\/radiobeat97.com.ar\/beat\/puesta-en-valor-del-parque-de-las-tejas-mas-juegos-para-ninos-iluminacion-y-espacios-para-actividad-fisica\/","title":{"rendered":"Puesta en valor del Parque de las Tejas: M\u00e1s juegos para ni\u00f1os, iluminaci\u00f3n y espacios para actividad f\u00edsica"},"content":{"rendered":"<ul class=\" wp-block-list eplus-wrapper eplus-styles-uid-c32852\">\n<li class=\" eplus-wrapper\"><strong>La Provincia ejecuta un plan integral para devolver funcionalidad y seguridad al paseo.<\/strong><\/li>\n<li class=\" eplus-wrapper\"><strong>La intervenci\u00f3n apunta a renovar la infraestructura y la din\u00e1mica del paseo que se convirti\u00f3 en un lugar de encuentro en el coraz\u00f3n de Nueva C\u00f3rdoba.<\/strong><\/li>\n<\/ul>\n<p class=\" eplus-wrapper\">El Gobierno de C\u00f3rdoba trabaja en la puesta en valor del Parque de las Tejas, ubicado en el barrio Nueva C\u00f3rdoba, donde anteriormente funcionaba la Casa de Gobierno.<\/p>\n<p class=\" eplus-wrapper\">La intervenci\u00f3n apunta a renovar la infraestructura y la din\u00e1mica del paseo, que se convirti\u00f3 en un lugar de encuentro y esparcimiento de la comunidad estudiantil universitaria y vecinos de la zona.<\/p>\n<p class=\" eplus-wrapper\">El proyecto integral incluye paisajismo, iluminaci\u00f3n, nuevos senderos, renovaci\u00f3n de mobiliario, espacios con juegos para ni\u00f1os y para actividad f\u00edsica de j\u00f3venes y adultos mayores.<\/p>\n<p class=\" eplus-wrapper\">Uno de los sectores con mayor intervenci\u00f3n es el Patio de las Infancias, sobre la calle Chile, donde se ejecutar\u00e1 una renovaci\u00f3n y el reemplazo total de las estructuras l\u00fadicas por equipamiento nuevo de alta calidad y gran envergadura para los usuarios m\u00e1s peque\u00f1os.<\/p>\n<p class=\" eplus-wrapper\">En tanto, la zona conocida como Patio de Ejercicios tendr\u00e1 987 metros cuadrados de solados nuevos que incluyen una superficie de 433 metros cuadrados de piso antigolpes realizado con caucho reciclado para amortiguar impactos.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped eplus-wrapper wp-block-gallery-1\">\n<figure class=\"wp-block-image size-full eplus-wrapper wp-lightbox-container\" data-wp-context=\"{&quot;imageId&quot;:&quot;69bbe212a7307&quot;}\" data-wp-interactive=\"core\/image\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-638458\" src=\"https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-1.jpeg\" sizes=\"(max-width: 987px) 100vw, 987px\" srcset=\"https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-1.jpeg 987w, https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-1-300x191.jpeg 300w, https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-1-768x489.jpeg 768w\" alt=\"\" width=\"987\" height=\"629\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" data-id=\"638458\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Agrandar\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\"><\/button><\/figure>\n<figure class=\"wp-block-image size-full eplus-wrapper wp-lightbox-container\" data-wp-context=\"{&quot;imageId&quot;:&quot;69bbe212a76f6&quot;}\" data-wp-interactive=\"core\/image\"><img decoding=\"async\" class=\"wp-image-638459\" src=\"https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-2.jpeg\" sizes=\"(max-width: 1280px) 100vw, 1280px\" srcset=\"https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-2.jpeg 1280w, https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-2-300x194.jpeg 300w, https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-2-1024x663.jpeg 1024w, https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-2-768x497.jpeg 768w\" alt=\"\" width=\"1280\" height=\"829\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" data-id=\"638459\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Agrandar\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\"><\/button><\/figure>\n<\/figure>\n<p class=\" eplus-wrapper\">Para una efectiva y segura pr\u00e1ctica deportiva, se contempla la instalaci\u00f3n de aparatos especializados de alta calidad para calistenia con carteler\u00eda espec\u00edfica y un dise\u00f1o apto para su utilizaci\u00f3n por parte de adultos mayores, fomentando as\u00ed la inclusi\u00f3n de diferentes franjas etarias en la actividad f\u00edsica al aire libre.<\/p>\n<p class=\" eplus-wrapper\">La puesta en valor se completa con la recuperaci\u00f3n integral de la fuente de chorros y la restauraci\u00f3n de esculturas existentes, placas y m\u00e1stiles.<\/p>\n<p class=\" eplus-wrapper\">El \u00e1rea se completar\u00e1 con la instalaci\u00f3n de mobiliario urbano y la construcci\u00f3n de un canil para mascotas que contar\u00e1 con un cerramiento perimetral conformado por un banco de hormig\u00f3n armado in situ y una reja met\u00e1lica.<\/p>\n<p class=\" eplus-wrapper\">La infraestructura de servicios constituye otro componente vital de la obra, por lo cual se planific\u00f3 la recuperaci\u00f3n de los ba\u00f1os p\u00fablicos, la recuperaci\u00f3n de wifi y de la infraestructura de iluminaci\u00f3n del parque con la incorporaci\u00f3n de nuevas torres con tecnolog\u00eda led.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped eplus-wrapper wp-block-gallery-2\">\n<figure class=\"wp-block-image size-large eplus-wrapper wp-lightbox-container\" data-wp-context=\"{&quot;imageId&quot;:&quot;69bbe212a7bdc&quot;}\" data-wp-interactive=\"core\/image\"><img decoding=\"async\" class=\"wp-image-638461\" src=\"https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-4-1024x656.jpeg\" sizes=\"(max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-4-1024x656.jpeg 1024w, https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-4-300x192.jpeg 300w, https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-4-768x492.jpeg 768w, https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-4.jpeg 1271w\" alt=\"\" width=\"1024\" height=\"656\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" data-id=\"638461\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Agrandar\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\"><\/button><\/figure>\n<figure class=\"wp-block-image size-large eplus-wrapper wp-lightbox-container\" data-wp-context=\"{&quot;imageId&quot;:&quot;69bbe212a7f6e&quot;}\" data-wp-interactive=\"core\/image\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-638460\" src=\"https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-3-1024x676.jpeg\" sizes=\"(max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-3-1024x676.jpeg 1024w, https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-3-300x198.jpeg 300w, https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-3-768x507.jpeg 768w, https:\/\/prensa.cba.gov.ar\/wp-content\/uploads\/2026\/03\/parque-tejas-proyecto-render-3.jpeg 1267w\" alt=\"\" width=\"1024\" height=\"676\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-on-async--load=\"callbacks.setButtonStyles\" data-wp-on-async-window--resize=\"callbacks.setButtonStyles\" data-id=\"638460\" \/><button class=\"lightbox-trigger\" type=\"button\" aria-haspopup=\"dialog\" aria-label=\"Agrandar\" data-wp-init=\"callbacks.initTriggerButton\" data-wp-on-async--click=\"actions.showLightbox\" data-wp-style--right=\"state.imageButtonRight\" data-wp-style--top=\"state.imageButtonTop\"><\/button><\/figure>\n<\/figure>\n<h4 class=\" wp-block-heading eplus-wrapper\">Paisajismo<\/h4>\n<p class=\" eplus-wrapper\">El factor paisaj\u00edstico juega un rol fundamental en esta puesta en valor con el objeto de dotar al Parque de las Tejas de nuevos mantos vivos verdes y mayor sombra.<\/p>\n<p class=\" eplus-wrapper\">Se proyect\u00f3 la plantaci\u00f3n de m\u00e1s de 100 \u00e1rboles distribuidos estrat\u00e9gicamente en los distintos sectores para forestar \u00e1reas que se encontraban vac\u00edas y la instalaci\u00f3n de un sistema de riego por aspersi\u00f3n y goteo automatizado que incluye la recuperaci\u00f3n de la cisterna y los equipos existentes.<\/p>\n<p class=\" eplus-wrapper\">Asimismo, el proyecto contempla la reorganizaci\u00f3n de los senderos para la circulaci\u00f3n peatonal dentro del parque, para lo cual se realizar\u00e1n 630 metros cuadrados de solados nuevos.<\/p>\n<p class=\" eplus-wrapper\">El Parque de las Tejas fue inaugurado en 2011 en el predio donde anteriormente funcionaba la Casa de Gobierno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Provincia ejecuta un plan integral para devolver funcionalidad y seguridad al paseo. La intervenci\u00f3n apunta a renovar la infraestructura y la din\u00e1mica del paseo que se convirti\u00f3 en un lugar de encuentro en el coraz\u00f3n de Nueva C\u00f3rdoba. El Gobierno de C\u00f3rdoba trabaja en la puesta en valor del Parque de las Tejas, ubicado &hellip;<\/p>\n","protected":false},"author":1,"featured_media":7879,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50,48],"tags":[],"class_list":["post-7878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","category-info-general"],"_links":{"self":[{"href":"https:\/\/radiobeat97.com.ar\/beat\/wp-json\/wp\/v2\/posts\/7878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiobeat97.com.ar\/beat\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiobeat97.com.ar\/beat\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiobeat97.com.ar\/beat\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiobeat97.com.ar\/beat\/wp-json\/wp\/v2\/comments?post=7878"}],"version-history":[{"count":1,"href":"https:\/\/radiobeat97.com.ar\/beat\/wp-json\/wp\/v2\/posts\/7878\/revisions"}],"predecessor-version":[{"id":7880,"href":"https:\/\/radiobeat97.com.ar\/beat\/wp-json\/wp\/v2\/posts\/7878\/revisions\/7880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiobeat97.com.ar\/beat\/wp-json\/wp\/v2\/media\/7879"}],"wp:attachment":[{"href":"https:\/\/radiobeat97.com.ar\/beat\/wp-json\/wp\/v2\/media?parent=7878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiobeat97.com.ar\/beat\/wp-json\/wp\/v2\/categories?post=7878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiobeat97.com.ar\/beat\/wp-json\/wp\/v2\/tags?post=7878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}